{"id":11,"date":"2022-01-19T20:18:18","date_gmt":"2022-01-19T19:18:18","guid":{"rendered":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/?p=11"},"modified":"2022-03-07T15:29:50","modified_gmt":"2022-03-07T14:29:50","slug":"exemple-de-blog-format-d-i-e","status":"publish","type":"post","link":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/2022\/01\/19\/exemple-de-blog-format-d-i-e\/","title":{"rendered":"exemple de blog \/ format D.I.E."},"content":{"rendered":"<p><strong>Les toilettes unisexes<\/strong><\/p>\n<p><strong>Description<\/strong><\/p>\n<p>Un soir, je buvais un verre avec mon amie et je me suis excus<strong>\u00e9<\/strong> ainsi que pour aller aux toilettes. Comme d\u2019habitude en France, certaines salles ne cont<strong>ien<\/strong> que des toilettes reli<strong>\u00e9s<\/strong> \u00e0 une salle plus grande avec des lavabos. J\u2019ai quitt\u00e9 la salle de la toilette et quand j\u2019ai commenc\u00e9 \u00e0 me laver mes mains, j\u2019ai vu un homme sortir de la salle de la toilette \u00e0 c\u00f4t\u00e9 de la mienne. Pensant que je me suis tromp<strong>\u00e9<\/strong> et j\u2019\u00e9tais dans les toilettes des hommes, j\u2019ai tout de suite murmur\u00e9 que j\u2019\u00e9tais d\u00e9sol<strong>\u00e9<\/strong> et je suis par<strong>ti.<\/strong> Embarrass\u00e9e, je cherchais pour un panneau \u00e0 l&#8217;ext\u00e9rieur de v\u00e9rifier que c\u2019\u00e9tait vraiment des toilettes d\u2019hommes, mais curieusement, il n\u2019y en avait aucun. Je n\u2019avais aucune raison d&#8217;\u00eatre embarrass\u00e9, c\u2019\u00e9tait des toilettes unisexes!<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-336 alignleft\" src=\"http:\/\/blogs.dickinson.edu\/fr300printemps19\/files\/2019\/03\/bathroom-300x166.jpg\" alt=\"\" width=\"300\" height=\"166\" \/><\/p>\n<p><strong>Interpr\u00e9tation<\/strong><\/p>\n<p>Je suis reven<strong>u<\/strong> \u00e0 mon amie, qui est fran\u00e7aise, et nous avons bien rigo<strong>l\u00e9e.<\/strong> Honn\u00eatement, j\u2019avais paniqu\u00e9 pendant les deux minutes quand je pensais que j\u2019ai fait une erreur aussi maladroite<strong>.<\/strong> En Am\u00e9rique et en France les toilettes restent un espace tr\u00e8s priv<strong>\u00e9e<\/strong> dans les deux, j\u2019\u00e9tais\u00a0<span lang=\"fr\">s\u00fbre\u00a0<\/span>que je venais de m\u2019immiscer dans l\u2019intimit\u00e9 d\u2019un homme au hasard. Pas toutes les toilettes en France sont unisexes comme celle-l\u00e0, mais on les trouve fr\u00e9quemment. J\u2019ai demand\u00e9 \u00e0 mon amie pourquoi ce ph\u00e9nom\u00e8ne ne d\u00e9range pas les fran\u00e7ais, et elle a comment\u00e9 que les espaces tr\u00e8s priv\u00e9s, les salles des toilettes, sont tr\u00e8s s\u00e9par\u00e9es et ferm\u00e9es par rapport aux cabinets on trouve aux \u00c9tats Unis. Les genres partagent l\u2019espace seulement quand ils se lavent leurs mains.<\/p>\n<p><strong>Evaluation<\/strong><\/p>\n<p>C\u2019\u00e9tait un choc personnel, mais je suis s<span lang=\"fr\">\u00fb<\/span><strong>r<\/strong> que les fran\u00e7ais n\u2019y pensent pas \u00e0 deux fois. J&#8217;imagine que les fran\u00e7ais ne trouveraient pas les toilettes unisexes remarquables<strong>.<\/strong> L\u2019id\u00e9e d\u2019utiliser des toilettes unisexes comme celles-ci en France ne me met pas mal \u00e0 l\u2019aise, mais la comparaison est int\u00e9ressante car il y a r\u00e9cemment eu d\u2019importants d\u00e9bats aux \u00c9tats Unis concernant les toilettes que les personnes transgenres peuvent utiliser. Beaucoup de gens avaient des opinions bien arr\u00eat<strong>\u00e9s<\/strong>, mais ce probl\u00e8me ne va jamais arriver ici.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les toilettes unisexes Description Un soir, je buvais un verre avec mon amie et je me suis excus\u00e9 ainsi que pour aller aux toilettes. Comme d\u2019habitude en France, certaines salles ne contien que des toilettes reli\u00e9s \u00e0 une salle plus grande avec des lavabos. J\u2019ai quitt\u00e9 la salle de la toilette et quand j\u2019ai commenc\u00e9 [&hellip;]<\/p>\n","protected":false},"author":3176,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343264,343265,343262,343263,343266,343260,343261,1],"tags":[],"class_list":["post-11","post","type-post","status-publish","format-standard","hentry","category-17-mars","category-24-mars","category-le-10-fevrier","category-le-10-mars","category-le-18-mars-retour-sur-la-bd","category-le-27-janvier","category-le-3-fevrier","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/posts\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/users\/3176"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":0,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/posts\/11\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/media?parent=11"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/categories?post=11"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/tags?post=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}