{"id":189,"date":"2022-03-17T23:59:06","date_gmt":"2022-03-17T22:59:06","guid":{"rendered":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/?p=189"},"modified":"2022-03-17T23:59:06","modified_gmt":"2022-03-17T22:59:06","slug":"leffet-de-covid-sur-les-etudiants-francais","status":"publish","type":"post","link":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/2022\/03\/17\/leffet-de-covid-sur-les-etudiants-francais\/","title":{"rendered":"L&#8217;effet de COVID sur les \u00e9tudiants fran\u00e7ais"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.univ-tlse2.fr\/medias\/photo\/bandeau-rubrique-presentation-des-campus_1539876562104-png?ID_FICHE=90623\" alt=\"Les campus UT2J - Universit\u00e9 Toulouse - Jean Jaur\u00e8s\" \/><\/p>\n<p><strong>Description<\/strong><\/p>\n<p>Hier soir, dans le TD de mon cours de l\u2019histoire m\u00e9di\u00e9vale, mon professeur nous a donn\u00e9 nos partiels not\u00e9s. Mais, avant distribuer les partiels, il a dit que les notes ne sont pas tr\u00e8s bonnes en g\u00e9n\u00e9ral, et particuli\u00e8rement qu\u2019il y a les probl\u00e8mes de l\u2019orthographie et de suivre les m\u00e9thodes d\u2019\u00e9criture pour ce type de composition. Quand il a fini parler des erreurs dans les partiels, une fille a lev\u00e9 sa main et commenc\u00e9 d\u2019expliquer que les \u00e9tudiants dans le cours, et en ann\u00e9e deux en g\u00e9n\u00e9ral \u00e0 l\u2019universit\u00e9, sont dans un mauvais \u00e9tat \u00e0 cause du COVID. Juste apr\u00e8s le BAC, le confinement a commenc\u00e9 et les \u00e9tudiants ont pass\u00e9 la majorit\u00e9 de leurs exp\u00e9riences universitaire sur l\u2019Internet, o\u00f9 ils n\u2019ont pas appris aux m\u00eames qualit\u00e9s qu\u2019en personne. Et comme un r\u00e9sultat, ils re\u00e7oivent les commentaires comme mon professeur a dit, qui demandent pourquoi les \u00e9tudiants ne travaillent pas au niveau de leur ann\u00e9e actuelle. Et selon la fille de mon cours, les professeurs qui le dit ne sont pas toujours sympas quand ils font ces commentaires.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Interpr\u00e9tation<\/strong><\/p>\n<p>Au d\u00e9but, j\u2019ai \u00e9t\u00e9 surpris de r\u00e9aliser les \u00e9tudiants fran\u00e7ais dans mon cours sont aussi d\u00e9sorient\u00e9s et inqui\u00e9t\u00e9s, parce qu\u2019ils ont \u00e9lev\u00e9s dans le syst\u00e8me de la scolarit\u00e9 fran\u00e7ais et ils parlent la langue fran\u00e7aise comme leur langue maternelle. Mais, quand la fille a parl\u00e9 des commentaires des professeurs et comment faire l\u2019universit\u00e9 sur l\u2019Internet ne eux permet pas de pratiquer et apprendre les m\u00e9thodes d\u2019\u00e9critures, je peux comprendre. Surtout parce que les Fran\u00e7ais font trois ann\u00e9es d\u2019universit\u00e9 et pas quatre comme aux Etats-Unis, ils ont vraiment perdu une grande partie de leur entrainement au l\u2019universit\u00e9. Comme moi, j\u2019ai pu que mon professeur n\u2019a pas compris cette situation avant ; maintenant, il a cr\u00e9\u00e9 les petits entrainements pas not\u00e9s pour aider tous les \u00e9tudiants dans le cours de r\u00e9ussir pendant l\u2019examen finale en mai.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Evaluation<\/strong><\/p>\n<p>Bien qu\u2019il ne soit pas une grande observation culturelle, je pense qu\u2019il est un peu int\u00e9ressant de penser sur l\u2019effet de COVID sur les \u00e9tudiants dans un syst\u00e8me diff\u00e8rent de le mien. Les structures des assignements \u00e0 l\u2019universit\u00e9 fran\u00e7ais sont plus rigides dans mon exp\u00e9rience, donc si les \u00e9tudiants n\u2019apprennent pas bien dans leur premi\u00e8re ann\u00e9e sur l\u2019Internet, les professeurs ne le r\u00e9alisent pas et n\u2019enseignent pas comment le faire en la deuxi\u00e8me ann\u00e9e. Je pense qu\u2019il est tr\u00e8s important de consid\u00e9rer comment COVID a affect\u00e9 tous les syst\u00e8mes diff\u00e9rents, et comment d\u2019aider et accommoder les personnes affect\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Description Hier soir, dans le TD de mon cours de l\u2019histoire m\u00e9di\u00e9vale, mon professeur nous a donn\u00e9 nos partiels not\u00e9s. Mais, avant distribuer les partiels, il a dit que les notes ne sont pas tr\u00e8s bonnes en g\u00e9n\u00e9ral, et particuli\u00e8rement qu\u2019il y a les probl\u00e8mes de l\u2019orthographie et de suivre les m\u00e9thodes d\u2019\u00e9criture pour ce [&hellip;]<\/p>\n","protected":false},"author":4875,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343264],"tags":[],"class_list":["post-189","post","type-post","status-publish","format-standard","hentry","category-17-mars"],"_links":{"self":[{"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/posts\/189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/users\/4875"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/comments?post=189"}],"version-history":[{"count":0,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/posts\/189\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/media?parent=189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/categories?post=189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/tags?post=189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}