{"id":205,"date":"2022-03-18T12:19:03","date_gmt":"2022-03-18T11:19:03","guid":{"rendered":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/?p=205"},"modified":"2022-03-18T12:19:03","modified_gmt":"2022-03-18T11:19:03","slug":"les-cahiers-desther-histoires-de-mes-11-ans","status":"publish","type":"post","link":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/2022\/03\/18\/les-cahiers-desther-histoires-de-mes-11-ans\/","title":{"rendered":"Les Cahiers d&#8217;Esther: Histoires de mes 11 ans"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-218\" src=\"http:\/\/blogs.dickinson.edu\/fr300printemps2022\/files\/2022\/03\/IMG_0818-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/files\/2022\/03\/IMG_0818-225x300.jpeg 225w, https:\/\/blogs.dickinson.edu\/fr300printemps2022\/files\/2022\/03\/IMG_0818-768x1024.jpeg 768w, https:\/\/blogs.dickinson.edu\/fr300printemps2022\/files\/2022\/03\/IMG_0818-1152x1536.jpeg 1152w, https:\/\/blogs.dickinson.edu\/fr300printemps2022\/files\/2022\/03\/IMG_0818-1536x2048.jpeg 1536w, https:\/\/blogs.dickinson.edu\/fr300printemps2022\/files\/2022\/03\/IMG_0818-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/p>\n<p>1. Qu\u2019est-ce que cela vous fait ressentir ? d\u2019amusement? du chagrin? \u00e0 quoi cela vous fait r\u00e9fl\u00e9chir ?<\/p>\n<p>Quand j&#8217;ai lu cette BD, je me suis senti un peu confus. C&#8217;est parce que la BD est pour &#8220;L&#8217;histoire de mes 11 ans&#8221; et je ne me souviens pas de ma 11e ann\u00e9e de la m\u00eame mani\u00e8re. L&#8217;une des premi\u00e8res BDs du livre montre comment les gar\u00e7ons et les filles se recontrent amoureuses. Je crois que quand j&#8217;avais 11 ans, je ne savais m\u00eame pas ce qu&#8217;\u00e9taient les gar\u00e7ons ou ils avaient des &#8220;cooties&#8221;. Cependant cela a du sens aujourd&#8217;hui car les BDs ont \u00e9t\u00e9 publi\u00e9es en 2017 et les actions des jeunes ont beaucoup chang\u00e9 depuis que je suis jeune. Mais c&#8217;\u00e9tait amusant pour moi de les lire et de voir l&#8217;\u00e9volution de la fa\u00e7on dont les enfants s&#8217;impliquent. Dans mon\u00a0 \u00e9cole, il n&#8217;y a jamais eu aucune forme d&#8217;\u00e9lection \u00e0 l&#8217;\u00e9cole pour quoi que ce soit avant le lyc\u00e9e, mais maintenant aux \u00c9tats-Unis aussi, il y a des \u00e9lections pour tous les \u00e2ges. Je crois que c&#8217;est parce que tout le monde est encourag\u00e9 a s&#8217;impliquer maintenant.<\/p>\n<p>2. Apprenez-vous quelque chose sur la France ?<\/p>\n<p>Oui j&#8217;ai beaucoup appris. En particulier j&#8217;ai appris les diff\u00e9rences avec la vie des jeunes enfants et leur \u00e9cole. En France les enfants sont \u00e0 peu pr\u00e8s pareils aux \u00c9tats-Unis ce que je pensais que ce n&#8217;\u00e9tait pas le cas. La BD montre que beaucoup d&#8217;enfants veulent \u00eatre sur leur t\u00e9l\u00e9phone et regarder la t\u00e9l\u00e9vision, ce que je pensais que les enfants voulaient principalement faire des activit\u00e9s plus intellectuels. Mais Esther aime lire et veut que sa meilleure amie lise avec elle, cependant, Cassandre est une gamine qui veut le t\u00e9l\u00e9phone.<\/p>\n<p>3. Que pourrait-on dire sur lq relation du citoyen \u00e0 son identit\u00e9 son \u00e9tat ? \u00e0 son territoire au travers ce BD ?<\/p>\n<p>Esther est une citoyenne avec un longue histoire. Sa mere \u00e9tait Bretagne donc elle a pu parler avec un jeune fille qui parlait le dialecte de diwan. Aussi la BD se representerai Esther comme ayant une maison stable, mais la BD se representerai Cassandre dans une situation financi\u00e8re diff\u00e9rent. Je pense que l&#8217;identit\u00e9 de Esther et lui histoire est la raisson pour elle aime lire et plusieurs activites. Parce que la m\u00e8re de Cassandre est pauvre et le p\u00e8re \u00e9tait mort les activites plus compliqu\u00e9es sont plus difficiles \u00e0 faire pour sa m\u00e8re. La BD repr\u00e9sente les diff\u00e9rentes r\u00e9gions de la France ainsi que les diff\u00e9rents \u00e9tats de vie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1. Qu\u2019est-ce que cela vous fait ressentir ? d\u2019amusement? du chagrin? \u00e0 quoi cela vous fait r\u00e9fl\u00e9chir ? Quand j&#8217;ai lu cette BD, je me suis senti un peu confus. C&#8217;est parce que la BD est pour &#8220;L&#8217;histoire de mes 11 ans&#8221; et je ne me souviens pas de ma 11e ann\u00e9e de la m\u00eame [&hellip;]<\/p>\n","protected":false},"author":4548,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343266],"tags":[],"class_list":["post-205","post","type-post","status-publish","format-standard","hentry","category-le-18-mars-retour-sur-la-bd"],"_links":{"self":[{"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/posts\/205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/users\/4548"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/comments?post=205"}],"version-history":[{"count":0,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/posts\/205\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/media?parent=205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/categories?post=205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/tags?post=205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}