{"id":40,"date":"2022-01-31T01:04:56","date_gmt":"2022-01-31T00:04:56","guid":{"rendered":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/?p=40"},"modified":"2022-01-31T01:04:56","modified_gmt":"2022-01-31T00:04:56","slug":"les-vies-quotidiennes-dans-les-pyrenees","status":"publish","type":"post","link":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/2022\/01\/31\/les-vies-quotidiennes-dans-les-pyrenees\/","title":{"rendered":"Les vies quotidiennes dans les Pyr\u00e9n\u00e9es"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-37\" src=\"http:\/\/blogs.dickinson.edu\/fr300printemps2022\/files\/2022\/01\/20220122_122306-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/files\/2022\/01\/20220122_122306-300x225.jpg 300w, https:\/\/blogs.dickinson.edu\/fr300printemps2022\/files\/2022\/01\/20220122_122306-1024x768.jpg 1024w, https:\/\/blogs.dickinson.edu\/fr300printemps2022\/files\/2022\/01\/20220122_122306-768x576.jpg 768w, https:\/\/blogs.dickinson.edu\/fr300printemps2022\/files\/2022\/01\/20220122_122306-1536x1152.jpg 1536w, https:\/\/blogs.dickinson.edu\/fr300printemps2022\/files\/2022\/01\/20220122_122306-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><span style=\"font-weight: 400\">Description:<\/span><\/p>\n<p><span style=\"font-weight: 400\">Regardez cette image. Le ciel azur sans les nuages, les montagnes majestueuses qui montent aux tailles impossibles\u2013 c\u2019est mieux qu\u2019une carte postale.\u00a0 Mais si on la regarde plus proche, on peut voir deux petites villes qui sont planqu\u00e9es aux pieds des montagnes.\u00a0 Ces sont les villes du Vall\u00e9e du Louron dans les Hautes-Pyr\u00e9n\u00e9es. Il y a 14 communes en totale avec les populations entre 15 et 300 d\u00e9pendant de chaque ville. Le 22 janvier, on a fait une randonn\u00e9e dans les Pyr\u00e9n\u00e9es avec une guide locale (Madame Elisabeth) qui habite dans une de ces communes. Il faisait tr\u00e8s beau avec l\u2019air frais et la chaleur du soleil. On a mang\u00e9 sur un belv\u00e9d\u00e8re, explor\u00e9 des villes, et parl\u00e9 avec Madame Elisabeth.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Interpr\u00e9tation<\/span><span style=\"font-weight: 400\">:<\/span><\/p>\n<p><span style=\"font-weight: 400\">Pendant la randonn\u00e9e, je me demande quels types de gens habitent dans ces communes. Les vieux, les jeunes, les couples, les familles avec les enfants? Je ne peux pas croire comment on vit en r\u00e9veillant avec une vue comme \u00e7a chaque matin. Je me demande aussi si ce style de vie est assez isol\u00e9, s&#8217;il me semble. Est-ce qu\u2019il y a les march\u00e9s ou les \u00e9coles assez proches?\u00a0 Je ne peux pas imaginer comment \u00e7a va grandir dans une commune ici dans le Vall\u00e9e du Louron. J\u2019\u00e9tais choqu\u00e9 que les vrais gens habitent ici et les montagnes sont une partie de leur vie quotidienne. Dans ma t\u00eate, je le compare de ma ville chez moi au New Jersey o\u00f9 le supermarch\u00e9 est cinq minutes par voiture et l\u2019\u00e9cole et juste dans la rue prochaine.\u00a0 En m\u00eame temps, je pense d&#8217;une maison d\u2019un ami en Oregon qui est \u00e0 deux heures du supermarch\u00e9 le plus proche. \u00c9videmment, c\u2019est un diff\u00e9rent style de vie que mon enfance mais pour gagner le perspective d\u2019une locale du r\u00e9gion, j\u2019ai parl\u00e9 avec Madame Elisabeth.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Evaluation:<\/span><\/p>\n<p><span style=\"font-weight: 400\">Elle me dit que c\u2019est vraiment un m\u00e9lange de tout entre les habitants des communes.\u00a0 Il y a les vieux qui ont pass\u00e9 leur vies enti\u00e8res dans les Pyr\u00e9n\u00e9es, les couples d\u2019\u00e2ges m\u00fbrs et les couples plus jeunes avec les enfants.\u00a0 Les gens qui travaillent gagnent leurs vies comme fermiers, guides de tourisme, ou ouvriers \u00e0 l&#8217;usine hydro\u00e9lectrique. En plus, il n\u2019y a pas beaucoup d\u2019enfants donc il y a une \u00e9cole primaire pour toutes les communes dans le Vall\u00e9e Louron.\u00a0 Il y a aussi un lyc\u00e9e et apr\u00e8s \u00e7a, beaucoup de jeunes vont \u00e0 Toulouse ou Bordeaux s\u2019ils veulent continuer les \u00e9tudes. J\u2019ai exprim\u00e9 \u00e0 Madame Elisabeth que c\u2019\u00e9tait difficile d\u2019imaginer grandir dans cet endroit. Elle a r\u00e9pondu que \u00abquand \u00e7a c\u2019est qu\u2019on connait, \u00e7a c\u2019est simplement le norme\u00bb.\u00a0 Elle m\u2019a dit que souvent quand les autres jeunes arrivent, ils demandent \u00abo\u00f9 sont les magasins?\u00bb. Mais c\u2019est simplement une culture et un style de vie diff\u00e9rent et les jeunes dans les communes ne sont pas priv\u00e9s de choses sympa. Par contre, il n\u2019est pas trop inconv\u00e9nient parce que le supermarch\u00e9 le plus proche est 15 minutes par voiture. Dans l&#8217;ensemble, je ne sais pas si je peux vivre dans un endroit comme \u00e7a pour quelques ann\u00e9es mais c\u2019\u00e9tait tr\u00e8s beau et serein et le paysage me mettait en paix. C\u2019est une culture tr\u00e8s diff\u00e9rente de mon enfance aux \u00c9tats-Unis et aussi diff\u00e9rente de la culture que j\u2019ai d\u00e9j\u00e0 vu \u00e0 Toulouse.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Description: Regardez cette image. Le ciel azur sans les nuages, les montagnes majestueuses qui montent aux tailles impossibles\u2013 c\u2019est mieux qu\u2019une carte postale.\u00a0 Mais si on la regarde plus proche, on peut voir deux petites villes qui sont planqu\u00e9es aux pieds des montagnes.\u00a0 Ces sont les villes du Vall\u00e9e du Louron dans les Hautes-Pyr\u00e9n\u00e9es. Il [&hellip;]<\/p>\n","protected":false},"author":4860,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343260],"tags":[],"class_list":["post-40","post","type-post","status-publish","format-standard","hentry","category-le-27-janvier"],"_links":{"self":[{"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/posts\/40","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/users\/4860"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/comments?post=40"}],"version-history":[{"count":0,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/posts\/40\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/media?parent=40"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/categories?post=40"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/fr300printemps2022\/wp-json\/wp\/v2\/tags?post=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}