{"id":1470,"date":"2026-05-03T21:18:03","date_gmt":"2026-05-03T21:18:03","guid":{"rendered":"https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/?p=1470"},"modified":"2026-05-03T21:18:25","modified_gmt":"2026-05-03T21:18:25","slug":"paradis-sur-la-terre-lexploitation-de-la-polynesie","status":"publish","type":"post","link":"https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/2026\/05\/03\/paradis-sur-la-terre-lexploitation-de-la-polynesie\/","title":{"rendered":"Paradis sur la terre: L\u2019exploitation de la Polyn\u00e9sie"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Nous sommes \u00e0 la recherche de paradis puisque avant notre \u00e8re. R\u00e9ellement, le concept a \u00e9merg\u00e9 en Perse \u00e0 d\u00e9crire un verger ou un parc royal. Plus tard, le mot \u00e0 utiliser pour le jardin d\u2019\u00c9den (<\/span><a href=\"https:\/\/www.etymonline.com\/word\/paradise\"><span style=\"font-weight: 400\">Etymonline<\/span><\/a><span style=\"font-weight: 400\">). Un endroit mythique, avec la paix, le plaisir, et la grande joie. L\u2019endroit parfait pour les personnes, un paradis.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1471\" src=\"https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/files\/2026\/05\/unnamed-300x126.png\" alt=\"\" width=\"433\" height=\"182\" srcset=\"https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/files\/2026\/05\/unnamed-300x126.png 300w, https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/files\/2026\/05\/unnamed.png 512w\" sizes=\"auto, (max-width: 433px) 100vw, 433px\" \/><\/p>\n<p><span style=\"font-weight: 400\">[French Polynesia par Sophie Hurel, 2010. <\/span><a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:French_Polynesia_(29485347).jpeg\"><span style=\"font-weight: 400\">File:French Polynesia (29485347).jpeg<\/span><\/a><span style=\"font-weight: 400\">]\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">L\u2019explorer Louise Antoine de Bougainville \u00e0 arriver en Tahiti en 1768 apr\u00e8s, le capitaine englais Samuel Wallis a d\u00e9couvert les \u00eeles une ann\u00e9e avant. Quand Bougainville a vu la Polyn\u00e9sie pour la premi\u00e8re fois, il a pens\u00e9 que l&#8217;endroit \u00e9tait un paradis. Il a nomm\u00e9 l&#8217;\u00eele \u201cLa Nouvelle Cyth\u00e8re\u201d apr\u00e8s l&#8217;\u00eele grecque pour aphrodite, cr\u00e9ant l&#8217;id\u00e9e que polynesia \u00e9tait paradis (<\/span><a href=\"https:\/\/www.france.fr\/en\/article\/historical-and-cultural-melting-pot-french-polynesia-0\/#history-and-traditions-1\"><span style=\"font-weight: 400\">France.fr<\/span><\/a><span style=\"font-weight: 400\">).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Cette croyance que Polynesie \u00e9tait paradis sur la terre, a conduit l\u2019exploitation du pays et les st\u00e9r\u00e9otypes des habitants et leur culture. Ces st\u00e9r\u00e9otypes incluent un endroit avec n\u2019ont probl\u00e8mes pas et les habitants sont beaux, forts, et stupides avec une culture singuli\u00e8re ou une culture m\u00eame.\u00a0 A cause de cette croyance, la France a profit\u00e9 du pays puisque les polyn\u00e9siens voyaient facilement rempla\u00e7ables.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">CEP a commenc\u00e9 en 1963 et il a exist\u00e9 jusqu&#8217;en 1996, pendant ce temps, il y avait 193 explosions. Entre 1966 et 1974, l\u2019arm\u00e9e a proc\u00e9d\u00e9 \u00e0 46 explosions en plein air en Polyn\u00e9sie, ce qui est plus de contamination dans l&#8217;histoire de la program. La mission du CEP \u00e9tait de d\u00e9velopper et tester les t\u00eates nucl\u00e9aires pour la force de dissuasion (<\/span><a href=\"https:\/\/disclose.ngo\/fr\/article\/essais-nucleaires-en-polynesie-loi-pour-mettre-fin-au-deni-etat\"><span style=\"font-weight: 400\">Disclose<\/span><\/a><span style=\"font-weight: 400\">). Les retomb\u00e9es radioactives ont affect\u00e9 les personnes, l&#8217;environnement, et le paysage sociopolitique fabriquent pour au moins les habitants paradis \u00eatre enfer sur la terre (<\/span><a href=\"https:\/\/www.bbc.com\/news\/world-europe-56340159\"><span style=\"font-weight: 400\">BBC<\/span><\/a><span style=\"font-weight: 400\">).<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1472\" src=\"https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/files\/2026\/05\/unnamed-2-300x169.png\" alt=\"\" width=\"521\" height=\"293\" srcset=\"https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/files\/2026\/05\/unnamed-2-300x169.png 300w, https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/files\/2026\/05\/unnamed-2-1024x576.png 1024w, https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/files\/2026\/05\/unnamed-2-768x432.png 768w, https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/files\/2026\/05\/unnamed-2-1200x675.png 1200w, https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/files\/2026\/05\/unnamed-2.png 1536w\" sizes=\"auto, (max-width: 521px) 100vw, 521px\" \/><\/p>\n<p><span style=\"font-weight: 400\">[This French nuclear test took place over Mururoa Atoll in 1971 par BBC, 1971. <\/span><a href=\"https:\/\/www.bbc.com\/news\/world-europe-56340159\"><span style=\"font-weight: 400\">French nuclear tests contaminated 110,000 in Pacific, says study<\/span><\/a><span style=\"font-weight: 400\">]<\/span><\/p>\n<p><span style=\"font-weight: 400\">L\u2019information par les documents qui \u00e9taient rendre publique en 2021 trouve 110,000 polyn\u00e9siens affectaeint de les testes nucl\u00e9aires. Ce nombre a \u00e9t\u00e9 d&#8217;environ tout la population de la Polyn\u00e9sie a le temps des testes (<\/span><a href=\"https:\/\/disclose.ngo\/fr\/article\/revelations-sur-lheritage-toxique-des-essais-nucleaires-francais-en-polynesie\"><span style=\"font-weight: 400\">Disclose<\/span><\/a><span style=\"font-weight: 400\">). Les personnes (ainsi que les enfants) ont contract\u00e9 vingt-trois maladies radio-induites parce que l\u2019explosion. Le gouvernement couvert la trag\u00e9die et encore perp\u00e9tuent le st\u00e9r\u00e9otype de paradis sur la terre.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Les retomb\u00e9es radioactives prouvent que le st\u00e9r\u00e9otype du paradis est faux, mais il y a plusieurs id\u00e9es \u00e0 faire en Polyn\u00e9sie. Principalement au sujet de la culture, et des personnes qui sont indig\u00e8nes. La culture de la Polyn\u00e9sie est ancienne, riche, complexe, et pleine de fiert\u00e9. Contre le st\u00e9r\u00e9otype que la culture \u00e9tait ne signifie pas et que les personnes \u00e9taient sauvages, la culture actuellement cultiv\u00e9 la navigation extraordinaire, une identit\u00e9 forte, l\u2019art beau et une reconnaissance profonde pour les a\u00een\u00e9s de la communaut\u00e9.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Leur culture est vaste avec les produits couvrent la navigation \u00e0 l&#8217;art. Par exemple\u00a0 Plusieurs des productions culturelles sont une produit d&#8217;environnement, c\u2019est aussi ou l\u2019argent vient de. Par exemple l\u2019huile de mono\u00ef, les perles noires, les sculptures des bois et os. Par ces exemples, il est clair que l\u2019environnement est tr\u00e8s important pour la culture. La nature \u00e9tant polluante renforce que le pays n\u2019est pas le paradis et cette notion est un mensonge alors la France ne peut pas tenir responsable de la contamination.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Continue avec la culture, les pratiqu\u00e9s culturelles sont la navigation des \u00e9toiles, le tatouage, et la narration par la danse. La navigation polyn\u00e9sienne \u00e9tait une pratique ancienne ou les personnes utilisaient les \u00e9toiles, les houles, le vent, et les signaux animaliers. La pratique \u00e9tait en danger d&#8217;\u00eatre perdue \u00e0 cause de la modernisation et l\u2019occidentalisation, cependant il y a une mission dans la pacifique a sauv\u00e9 et r\u00e9apprendre la pratique (<\/span><a href=\"https:\/\/hokulea.com\/polynesian-wayfinding\/\"><span style=\"font-weight: 400\">Polynesian Voyaging Society<\/span><\/a><span style=\"font-weight: 400\">). La tatouage symbolise la tradition, la g\u00e9n\u00e9alogie, le statut social, et la protection. L\u2019art est <\/span><span style=\"font-weight: 400\">caract\u00e9ris\u00e9<\/span> <span style=\"font-weight: 400\">par des motifs g\u00e9om\u00e9triques noirs et audacieux, des spirales et des motifs tels que des dents de requin et des figures tiki. La danse est de plus d\u2019importance pour la culture. L\u2019art est int\u00e9gral pour la pr\u00e9servation d&#8217;histoire et garde la tradition en vie.\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1473\" src=\"https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/files\/2026\/05\/unnamed-3-300x225.png\" alt=\"\" width=\"519\" height=\"389\" srcset=\"https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/files\/2026\/05\/unnamed-3-300x225.png 300w, https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/files\/2026\/05\/unnamed-3-1024x767.png 1024w, https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/files\/2026\/05\/unnamed-3-768x575.png 768w, https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/files\/2026\/05\/unnamed-3-1200x898.png 1200w, https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/files\/2026\/05\/unnamed-3.png 1408w\" sizes=\"auto, (max-width: 519px) 100vw, 519px\" \/><\/p>\n<p><span style=\"font-weight: 400\">[<\/span><span style=\"font-weight: 400\">Danses indig\u00e8nes \u00e0 Tahiti par <\/span><span style=\"font-weight: 400\">Agence Rol. Agence photographique, 1929. <\/span><a href=\"https:\/\/gallica.bnf.fr\/ark:\/12148\/btv1b532176105.r=Polynesia?rk=493564;4\"><span style=\"font-weight: 400\">https:\/\/gallica.bnf.fr\/ark:\/12148\/btv1b532176105.r=Polynesia?rk=493564;4#<\/span><\/a><span style=\"font-weight: 400\">]\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Pendant plusieurs ann\u00e9es les tropicales \u00eeles de la Polyn\u00e9sie ont d\u00e9crit le paradis. Ce st\u00e9r\u00e9otype a diminu\u00e9 le pays histoire, culture, et significance. Le pays souffrit par la colonisation et c\u2019est un endroit vrai, n&#8217;\u00e9tait pas un paradis pour les personnes qui veulent les esclaves dans un endroit exotique pour une semaine.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Ouvrages cit\u00e9s\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">\u201cFrench Nuclear Tests Contaminated 110,000 in Pacific, Says Study.\u201d <\/span><i><span style=\"font-weight: 400\">BBC News<\/span><\/i><span style=\"font-weight: 400\">, BBC, 9 Mar. 2021, www.bbc.com\/news\/world-europe-56340159.\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400\">Disclose.Ngo<\/span><\/i><span style=\"font-weight: 400\">, 20 Feb. 2026, disclose.ngo\/fr\/article\/essais-nucleaires-en-polynesie-loi-pour-mettre-fin-au-deni-etat.\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400\">Disclose.Ngo<\/span><\/i><span style=\"font-weight: 400\">, 9 Mar. 2021, disclose.ngo\/fr\/article\/revelations-sur-lheritage-toxique-des-essais-nucleaires-francais-en-polynesie. e<\/span><\/p>\n<p><span style=\"font-weight: 400\">Harper, Douglas. &#8220;Etymology of paradise.&#8221; Online Etymology Dictionary, https:\/\/www.etymonline.com\/word\/paradise. Accessed 1 May, 2026.<\/span><\/p>\n<p><span style=\"font-weight: 400\">\u201cA Historical and Cultural Melting Pot in French Polynesia.\u201d <\/span><i><span style=\"font-weight: 400\">FRANCE.FR<\/span><\/i><span style=\"font-weight: 400\">, 1 Sept. 2013, www.france.fr\/en\/article\/historical-and-cultural-melting-pot-french-polynesia-0\/#history-and-traditions-1.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">\u201cPolynesian Wayfinding.\u201d <\/span><i><span style=\"font-weight: 400\">H\u014dk\u016ble\u02bba<\/span><\/i><span style=\"font-weight: 400\">, 28 Aug. 2024, hokulea.com\/polynesian-wayfinding\/. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous sommes \u00e0 la recherche de paradis puisque avant notre \u00e8re. R\u00e9ellement, le concept a \u00e9merg\u00e9 en Perse \u00e0 d\u00e9crire un verger ou un parc royal. Plus tard, le mot \u00e0 utiliser pour le jardin d\u2019\u00c9den (Etymonline). Un endroit mythique, avec la paix, le plaisir, et la grande joie. L\u2019endroit parfait pour les personnes, un [&hellip;]<\/p>\n","protected":false},"author":5846,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,348030],"tags":[],"class_list":["post-1470","post","type-post","status-publish","format-standard","hentry","category-blog","category-other-francophone-countries"],"_links":{"self":[{"href":"https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/wp-json\/wp\/v2\/posts\/1470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/wp-json\/wp\/v2\/users\/5846"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/wp-json\/wp\/v2\/comments?post=1470"}],"version-history":[{"count":1,"href":"https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/wp-json\/wp\/v2\/posts\/1470\/revisions"}],"predecessor-version":[{"id":1474,"href":"https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/wp-json\/wp\/v2\/posts\/1470\/revisions\/1474"}],"wp:attachment":[{"href":"https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/wp-json\/wp\/v2\/media?parent=1470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/wp-json\/wp\/v2\/categories?post=1470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/frenchstudyabroad\/wp-json\/wp\/v2\/tags?post=1470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}