{"id":299,"date":"2020-05-11T00:37:52","date_gmt":"2020-05-11T00:37:52","guid":{"rendered":"http:\/\/blogs.dickinson.edu\/german-dept\/files\/2014\/04\/Gartenfest2020125_1.jpg"},"modified":"2020-05-11T00:37:52","modified_gmt":"2020-05-11T00:37:52","slug":"gartenfest2020125_1","status":"inherit","type":"attachment","link":"https:\/\/blogs.dickinson.edu\/german-dept\/2014\/04\/27\/photo-galleries-from-past-events\/gartenfest2020125_1\/","title":{"rendered":"Gartenfest2020125_1"},"author":4116,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-299","attachment","type-attachment","status-inherit","hentry","first-post"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blogs.dickinson.edu\/german-dept\/files\/2014\/04\/Gartenfest2020125_1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/blogs.dickinson.edu\/german-dept\/files\/2014\/04\/Gartenfest2020125_1-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/blogs.dickinson.edu\/german-dept\/files\/2014\/04\/Gartenfest2020125_1-300x225.jpg 300w, https:\/\/blogs.dickinson.edu\/german-dept\/files\/2014\/04\/Gartenfest2020125_1-320x240.jpg 320w, https:\/\/blogs.dickinson.edu\/german-dept\/files\/2014\/04\/Gartenfest2020125_1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":400,"height":300,"file":"2014\/04\/Gartenfest2020125_1.jpg","sizes":{"medium":{"file":"Gartenfest2020125_1-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.dickinson.edu\/german-dept\/files\/2014\/04\/Gartenfest2020125_1-300x225.jpg"},"thumbnail":{"file":"Gartenfest2020125_1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.dickinson.edu\/german-dept\/files\/2014\/04\/Gartenfest2020125_1-150x150.jpg"},"fd-sm":{"file":"Gartenfest2020125_1-320x240.jpg","width":320,"height":240,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.dickinson.edu\/german-dept\/files\/2014\/04\/Gartenfest2020125_1-320x240.jpg"},"full":{"file":"Gartenfest2020125_1.jpg","width":400,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.dickinson.edu\/german-dept\/files\/2014\/04\/Gartenfest2020125_1.jpg"}},"image_meta":{"aperture":"4.5","credit":"","camera":"Canon PowerShot SX100 IS","caption":"","created_timestamp":"1335199692","copyright":"","focal_length":"6","iso":"800","shutter_speed":"0.05","title":"","orientation":"1","keywords":[]}},"post":154,"source_url":"https:\/\/blogs.dickinson.edu\/german-dept\/files\/2014\/04\/Gartenfest2020125_1.jpg","filename":"Gartenfest2020125_1.jpg","filesize":30416,"_links":{"self":[{"href":"https:\/\/blogs.dickinson.edu\/german-dept\/wp-json\/wp\/v2\/media\/299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.dickinson.edu\/german-dept\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blogs.dickinson.edu\/german-dept\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/german-dept\/wp-json\/wp\/v2\/users\/4116"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/german-dept\/wp-json\/wp\/v2\/comments?post=299"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":154,"href":"https:\/\/blogs.dickinson.edu\/german-dept\/wp-json\/wp\/v2\/posts\/154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}