{"id":33,"date":"2011-02-23T15:11:20","date_gmt":"2011-02-23T15:11:20","guid":{"rendered":"http:\/\/blogs.dickinson.edu\/lalc\/files\/2011\/02\/cropped-pin03_la6xd5nc.jpg"},"modified":"2011-02-23T15:11:20","modified_gmt":"2011-02-23T15:11:20","slug":"cropped-pin03_la6xd5nc-jpg","status":"inherit","type":"attachment","link":"https:\/\/blogs.dickinson.edu\/lalc\/cropped-pin03_la6xd5nc-jpg\/","title":{"rendered":"cropped-pin03_la6xd5nc.jpg"},"author":778,"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"class_list":["post-33","attachment","type-attachment","status-inherit","hentry","post-preview"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blogs.dickinson.edu\/lalc\/files\/2011\/02\/cropped-pin03_la6xd5nc.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"63\" src=\"https:\/\/blogs.dickinson.edu\/lalc\/files\/2011\/02\/cropped-pin03_la6xd5nc-300x63.jpg\" class=\"attachment-medium size-medium\" alt=\"cropped pin laxdnc\" srcset=\"https:\/\/blogs.dickinson.edu\/lalc\/files\/2011\/02\/cropped-pin03_la6xd5nc-300x63.jpg 300w, https:\/\/blogs.dickinson.edu\/lalc\/files\/2011\/02\/cropped-pin03_la6xd5nc.jpg 940w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>http:\/\/blogs.dickinson.edu\/lalc\/files\/2011\/02\/cropped-pin03_la6xd5nc.jpg<\/p>\n"},"caption":{"rendered":"<p>http:\/\/blogs.dickinson.edu\/lalc\/files\/2011\/02\/cropped-pin03_la6xd5nc.jpg<\/p>\n"},"alt_text":"cropped pin laxdnc","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"940","height":"198","hwstring_small":"height='26' width='128'","file":"2011\/02\/cropped-pin03_la6xd5nc.jpg","sizes":{"thumbnail":{"file":"cropped-pin03_la6xd5nc-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/blogs.dickinson.edu\/lalc\/files\/2011\/02\/cropped-pin03_la6xd5nc-150x150.jpg"},"medium":{"file":"cropped-pin03_la6xd5nc-300x63.jpg","width":"300","height":"63","source_url":"https:\/\/blogs.dickinson.edu\/lalc\/files\/2011\/02\/cropped-pin03_la6xd5nc-300x63.jpg"},"single-thumb":{"file":"cropped-pin03_la6xd5nc-620x198.jpg","width":"620","height":"198","source_url":"https:\/\/blogs.dickinson.edu\/lalc\/files\/2011\/02\/cropped-pin03_la6xd5nc-620x198.jpg"},"sidebar-thumb":{"file":"cropped-pin03_la6xd5nc-36x36.jpg","width":"36","height":"36","source_url":"https:\/\/blogs.dickinson.edu\/lalc\/files\/2011\/02\/cropped-pin03_la6xd5nc-36x36.jpg"},"featured-slideshow-thumb":{"file":"cropped-pin03_la6xd5nc-640x198.jpg","width":"640","height":"198","source_url":"https:\/\/blogs.dickinson.edu\/lalc\/files\/2011\/02\/cropped-pin03_la6xd5nc-640x198.jpg"},"node-based-thumb":{"file":"cropped-pin03_la6xd5nc-195x110.jpg","width":"195","height":"110","source_url":"https:\/\/blogs.dickinson.edu\/lalc\/files\/2011\/02\/cropped-pin03_la6xd5nc-195x110.jpg"},"quick-preview-thumb":{"file":"cropped-pin03_la6xd5nc-115x115.jpg","width":"115","height":"115","source_url":"https:\/\/blogs.dickinson.edu\/lalc\/files\/2011\/02\/cropped-pin03_la6xd5nc-115x115.jpg"},"full":{"file":"cropped-pin03_la6xd5nc.jpg","width":940,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.dickinson.edu\/lalc\/files\/2011\/02\/cropped-pin03_la6xd5nc.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":null,"source_url":"https:\/\/blogs.dickinson.edu\/lalc\/files\/2011\/02\/cropped-pin03_la6xd5nc.jpg","_links":{"self":[{"href":"https:\/\/blogs.dickinson.edu\/lalc\/wp-json\/wp\/v2\/media\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.dickinson.edu\/lalc\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blogs.dickinson.edu\/lalc\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/lalc\/wp-json\/wp\/v2\/users\/778"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.dickinson.edu\/lalc\/wp-json\/wp\/v2\/comments?post=33"}]}}